{"id":915,"date":"2022-02-22T11:23:27","date_gmt":"2022-02-22T10:23:27","guid":{"rendered":"http:\/\/bernanos.org\/?p=915"},"modified":"2024-07-27T21:00:58","modified_gmt":"2024-07-27T19:00:58","slug":"nouvelles-et-appel-aux-dons","status":"publish","type":"post","link":"https:\/\/bernanos.org\/index.php\/2022\/02\/22\/nouvelles-et-appel-aux-dons\/","title":{"rendered":"Nouvelles et appel aux dons"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"915\" class=\"elementor elementor-915\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b825dd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b825dd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9bb7ce\" data-id=\"d9bb7ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e40bd41 elementor-widget elementor-widget-text-editor\" data-id=\"e40bd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 0cm 0cm 19.2pt; text-align: justify; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><font face=\"Calibri, sans-serif\"><span style=\"font-size: 15.3333px;\">Comme tant d\u2019autres, presque tous les jeunes accueillis \u00e0 Bernanos ont repris le chemin du lyc\u00e9e lundi dernier, et quelques-uns continuent de suivre des cours de fran\u00e7ais et de math\u00e9matiques en vue de leur scolarisation en septembre. Les a\u00een\u00e9s qui les ont pr\u00e9c\u00e9d\u00e9s, certains depuis des ann\u00e9es, sont maintenant ind\u00e9pendants, travaillent \u00e0 l\u2019obtention de leur CAP ou Bac Pro, louent leur petit studio \u00e0 Strasbourg. La voie est maintenant ouverte, l\u2019horizon plus clair. Les jeunes qui sont arriv\u00e9s \u00e0 Bernanos, apr\u00e8s un parcours migratoire bien douloureux, peuvent d\u00e9sormais envisager plus sereinement les mois ou les ann\u00e9es qu\u2019ils vivront chez nous ; si certains ne quitteront pas notre maison pour \u00eatre pris en charge par les structures d\u00e9di\u00e9es aux mineurs non-accompagn\u00e9s, ils savent qu\u2019avec patience, avec de la pers\u00e9v\u00e9rance dans leur formation professionnelle, et en allant \u00e0 la rencontre du large r\u00e9seau dont ils b\u00e9n\u00e9ficient \u00e0 travers notre association, ils peuvent esp\u00e9rer s\u2019int\u00e9grer, un jour, en France. Les relations de confiance construites entre l\u2019\u00e9quipe d\u2019accueil et les diff\u00e9rentes institutions ont permis bien des avanc\u00e9es que nous n\u2019envisagions pas il y a cinq ans, lorsque les premiers jeunes sont arriv\u00e9s chez nous.&nbsp;<\/span><\/font><\/p>\n<p style=\"margin: 0cm 0cm 19.2pt; text-align: justify; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><font face=\"Calibri, sans-serif\"><span style=\"font-size: 15.3333px;\">Ainsi, l\u2019accueil et l\u2019accompagnement des jeunes r\u00e9fugi\u00e9s se poursuit, se consolide, et emploie d\u00e9sormais 6 salari\u00e9s qui travaillent aux diff\u00e9rentes missions quotidiennes : l\u2019accompagnement \u00e9ducatif, la communication, la recherche de fonds, la sant\u00e9, l\u2019int\u00e9gration, la culture et le sport, la restauration, l&rsquo;entretien des locaux. Il y a cinq ans, comme nous venions de commencer \u00e0 accueillir les premiers jeunes, nous avons d\u00fb d\u00e9marrer des travaux de r\u00e9am\u00e9nagement des locaux afin qu\u2019ils r\u00e9pondent aux normes de s\u00e9curit\u00e9, et qu\u2019ils soient moins pr\u00e9caires pour le sommeil. La pand\u00e9mie a plus que ralentie la mise en \u0153uvre de ce chantier, qui ne vient que de commencer. Aussi, de nouveaux travaux, n\u00e9cessaires, ce sont ajout\u00e9s \u00e0 ceux pr\u00e9vus initialement. L\u2019encadrement par des professionnels, devenu imp\u00e9ratif pour passer d\u2019un accueil d\u2019abord provisoire \u00e0 un accueil structur\u00e9 et s\u2019inscrivant dans le temps, a aussi fortement augment\u00e9 les charges annuelles.&nbsp;<\/span><\/font><\/p>\n<p style=\"margin: 0cm 0cm 19.2pt; text-align: justify; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><font face=\"Calibri, sans-serif\"><span style=\"font-size: 15.3333px;\">Afin de faire face \u00e0 ces lourdes d\u00e9penses qui nous pressent, nous faisons appel \u00e0 vous. Votre soutien a \u00e9t\u00e9 une grande composante depuis les d\u00e9buts de l\u2019accueil des jeunes \u00e0 Bernanos. Il montre combien des citoyens ont la capacit\u00e9 de mettre en \u0153uvre leur d\u00e9sir d\u2019\u00eatre avec ceux que les conflits et la mis\u00e8re viennent d\u00e9placer, \u00e0 la recherche d\u2019un refuge pour prot\u00e9ger leur vie. Au nom de toute l\u2019\u00e9quipe, je vous dis ma profonde reconnaissance.&nbsp;<\/span><\/font><\/p><p style=\"margin: 0cm 0cm 19.2pt; text-align: justify; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><font face=\"Calibri, sans-serif\"><span style=\"font-size: 15.3333px;\">Thomas Wender<\/span><\/font><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ebce559 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebce559\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c075985\" data-id=\"c075985\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce59015 elementor-widget elementor-widget-button\" data-id=\"ce59015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.helloasso.com\/associations\/centre-bernanos\/formulaires\/2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire un don sur HelloAsso<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49f3bb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49f3bb3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3937de\" data-id=\"a3937de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d94d46 elementor-widget elementor-widget-image\" data-id=\"7d94d46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-1024x683.jpg\" class=\"attachment-large size-large wp-image-917\" alt=\"Jeunes de Bernanos avec un \u00e9ducateur dans la neige\" srcset=\"https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-1024x683.jpg 1024w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-300x200.jpg 300w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-768x512.jpg 768w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-1536x1024.jpg 1536w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Sortie-champ-du-feu-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4decbf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4decbf4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcc23e2\" data-id=\"fcc23e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09b6c5d elementor-widget elementor-widget-image\" data-id=\"09b6c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Balade.jpg\" class=\"attachment-large size-large wp-image-918\" alt=\"Jeunes de Bernanos avec les \u00e9ducateurs\" srcset=\"https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Balade.jpg 960w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Balade-300x225.jpg 300w, https:\/\/bernanos.org\/wp-content\/uploads\/2022\/06\/Balade-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comme tant d\u2019autres, presque tous les jeunes accueillis \u00e0 Bernanos ont repris le chemin du lyc\u00e9e lundi dernier, et quelques-uns continuent de suivre des cours de fran\u00e7ais et de math\u00e9matiques en vue de leur scolarisation en septembre. Les a\u00een\u00e9s qui les ont pr\u00e9c\u00e9d\u00e9s, certains depuis des ann\u00e9es, sont maintenant ind\u00e9pendants, travaillent \u00e0 l\u2019obtention de leur [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[],"class_list":["post-915","post","type-post","status-publish","format-standard","hentry","category-appel-aux-dons"],"_links":{"self":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":3,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/915\/revisions"}],"predecessor-version":[{"id":2871,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/915\/revisions\/2871"}],"wp:attachment":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/media?parent=915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/categories?post=915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/tags?post=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}