{"id":3278,"date":"2025-05-27T09:52:20","date_gmt":"2025-05-27T07:52:20","guid":{"rendered":"https:\/\/bernanos.org\/?p=3278"},"modified":"2026-01-13T11:13:03","modified_gmt":"2026-01-13T10:13:03","slug":"appel-aux-dons","status":"publish","type":"post","link":"https:\/\/bernanos.org\/index.php\/2025\/05\/27\/appel-aux-dons\/","title":{"rendered":"Appel aux dons"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3278\" class=\"elementor elementor-3278\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2b37a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2b37a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25efc50\" data-id=\"25efc50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a132c14 elementor-widget elementor-widget-text-editor\" data-id=\"a132c14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"font-size: 16px;\">Jean-Mickael, Alpha\u2026 et tant d&rsquo;autres jeunes ont trouv\u00e9 refuge, espoir et avenir au Centre Bernanos. Gr\u00e2ce \u00e0 votre soutien, des vies caboss\u00e9es deviennent des parcours inspirants. <\/span><\/div><div>\u00a0<\/div><div><span style=\"font-size: 16px;\">Aujourd\u2019hui, nous lan\u00e7ons un nouvel appel \u00e0 dons pour continuer \u00e0 accueillir, accompagner et reconstruire. Chaque geste compte. <\/span><img decoding=\"async\" style=\"font-style: inherit; font-weight: inherit;\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6c\/1\/16\/2764.png\" alt=\"\u2764\ufe0f\" width=\"16\" height=\"16\" \/><\/div><div><div dir=\"auto\">\u00a0<\/div><div dir=\"auto\">Lettre d\u00e9taill\u00e9e du directeur :\u00a0<\/div><div dir=\"auto\">\u00a0<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47ab9d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47ab9d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-794687e\" data-id=\"794687e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c373aa9 elementor-widget elementor-widget-text-editor\" data-id=\"c373aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Chers amis,<\/span><\/p><p><span style=\"font-weight: 400;\">La semaine derni\u00e8re, un jeune ivoirien accueilli au Centre Bernanos il y a quelques ann\u00e9es, Jean-Mickael, est venu nous rendre visite. Il rentrait d\u2019un chantier de construction d\u2019une piscine chez un particulier \u00e0 Strasbourg. Jean-Mickael a maintenant sa propre entreprise. Quel chemin parcouru depuis le jour o\u00f9 il est arriv\u00e9 au Centre Bernanos, dans un mutisme d\u00fb \u00e0 sa vie dans la rue depuis son arriv\u00e9e en France. Jean-Micka\u00ebl souhaite nous aider financi\u00e8rement et offrir de temps en temps un sac de riz.<\/span><\/p><p><span style=\"font-weight: 400;\">Hier, c\u2019\u00e9tait Alpha, jeune guin\u00e9en, qui apr\u00e8s un d\u00e9but de formation professionnelle en boulangerie au Lyc\u00e9e Charles de Foucauld \u00e0 Schiltigheim, avait d\u00fb se s\u00e9parer douloureusement de Strasbourg et de ses amis du Centre Bernanos, car une fois reconnu mineur, il avait \u00e9t\u00e9 affect\u00e9 au d\u00e9partement de Ch\u00e2lons-en-Champagne. Alpha est venu avec sa jeune fille et son \u00e9pouse, architecte. Quel beau parcours, dont il \u00e9tait difficile de percevoir le germe quand il est arriv\u00e9 au Centre Bernanos, lui aussi, bien abim\u00e9 par son parcours migratoire.<\/span><\/p><p><span style=\"font-weight: 400;\">Ce sont des histoires comme celles de Jean-Mickael et Alpha qui rempliront les pages du livre dont la publication se pr\u00e9pare pour cet \u00e9t\u00e9 ; projet soutenu par \u00ab Strasbourg capitale du livre \u00bb \u00e0 l\u2019initiative de l\u2019UNESCO. Apercevoir la lumi\u00e8re dans de jeunes vies bris\u00e9es est sans doute ce qui est le plus difficile lors des premiers temps de l\u2019accueil des jeunes au Centre Bernanos. Les visites r\u00e9guli\u00e8res, presque quotidiennes, des anciens de Bernanos, sont un pr\u00e9cieux soutien pour les nouveaux, qui comprennent \u00e0 travers le t\u00e9moignage de leurs a\u00een\u00e9s, qu\u2019eux aussi vont s\u2019en sortir.<\/span><\/p><p><span style=\"font-weight: 400;\">L\u2019accueil des jeunes filles a sans doute \u00e9t\u00e9 le plus grand d\u00e9fi relev\u00e9 l\u2019ann\u00e9e pass\u00e9e. Que de drames marquent leur esprit et leurs corps&#8230; Si elles ont toujours \u00e9t\u00e9 aussi nombreuses que les<\/span><\/p><p><span style=\"font-weight: 400;\">gar\u00e7ons \u00e0 arriver en France, elles disparaissaient tr\u00e8s vite dans des r\u00e9seaux de traites humaines. Voil\u00e0 que de plus en plus elles y \u00e9chappent. Quel courage ! Notre accueil s\u2019est tr\u00e8s vite adapt\u00e9 quand elles ont commenc\u00e9 \u00e0 frapper \u00e0 notre porte. Leur pr\u00e9sence est all\u00e9e jusqu\u2019\u00e0 nous faire modifier les statuts de notre association pour y inscrire la parit\u00e9 des b\u00e9n\u00e9ficiaires.<\/span><\/p><p><span style=\"font-weight: 400;\">Une professionnalisation toujours plus grande, et l\u2019apport de comp\u00e9tences toujours aussi<\/span><\/p><p><span style=\"font-weight: 400;\">important de la soci\u00e9t\u00e9 civile, contribuent \u00e0 consolider notre augmentation r\u00e9guli\u00e8re du nombre de b\u00e9n\u00e9ficiaires. La r\u00e9alisation de plans, de travaux, sont une r\u00e9alit\u00e9 permanente de la maison.<\/span><\/p><p><span style=\"font-weight: 400;\">Le Conseil d\u2019Administration de l\u2019association sera invit\u00e9 \u00e0 travailler sur une forme de cartographie des diff\u00e9rentes composantes qui rendent possible l\u2019accueil des jeunes migrants : qu\u2019il s\u2019agisse des partenaires financiers, de l\u2019\u00e9quipe \u00e9ducative, de la gestion, des partenaires op\u00e9rationnels (\u00e9coles, lyc\u00e9es professionnels, \u00e9tablissement de sant\u00e9, &#8230;), de l\u2019implication des b\u00e9n\u00e9voles et de la soci\u00e9t\u00e9 civile, de la dimension de protection de l\u2019environnement, du r\u00e9seau des entreprises qui accueillent les jeunes pour leurs stages et leur premier emploi, les liens avec les Collectivit\u00e9s, et tant d\u2019autres acteurs qui constituent le r\u00e9seau du Centre Bernanos.<\/span><\/p><p><span style=\"font-weight: 400;\">Votre soutien nous est tr\u00e8s pr\u00e9cieux. Nous maintenons un accueil avec des moyens simples et<\/span><\/p><p><span style=\"font-weight: 400;\">une vie quotidienne marqu\u00e9e par la sobri\u00e9t\u00e9.<\/span><\/p><p><span style=\"font-weight: 400;\">Avec beaucoup de reconnaissance,<\/span><\/p><p><span style=\"font-weight: 400;\">Thomas<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bd1bb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bd1bb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d5fa68\" data-id=\"9d5fa68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da48bf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9da48bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire un don<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jean-Mickael, Alpha\u2026 et tant d&rsquo;autres jeunes ont trouv\u00e9 refuge, espoir et avenir au Centre Bernanos. Gr\u00e2ce \u00e0 votre soutien, des vies caboss\u00e9es deviennent des parcours inspirants. \u00a0Aujourd\u2019hui, nous lan\u00e7ons un nouvel appel \u00e0 dons pour continuer \u00e0 accueillir, accompagner et reconstruire. Chaque geste compte. \u00a0Lettre d\u00e9taill\u00e9e du directeur :\u00a0\u00a0 Chers amis, La semaine derni\u00e8re, un [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3278","post","type-post","status-publish","format-standard","hentry","category-appel-aux-dons"],"_links":{"self":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/3278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/comments?post=3278"}],"version-history":[{"count":12,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/3278\/revisions"}],"predecessor-version":[{"id":3342,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/posts\/3278\/revisions\/3342"}],"wp:attachment":[{"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/media?parent=3278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/categories?post=3278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bernanos.org\/index.php\/wp-json\/wp\/v2\/tags?post=3278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}